{"id":29123642,"date":"2025-03-13T00:27:39","date_gmt":"2025-03-13T00:27:39","guid":{"rendered":"https:\/\/www.inmobrisa.com\/inmueble\/venta\/apartamento\/alicante\/san-juan-de-alicante-sant-joan-d-alacant\/n8236\/"},"modified":"2025-03-13T00:27:39","modified_gmt":"2025-03-13T00:27:39","slug":"venta-de-apartamento-en-san-juan-de-alicante-sant-joan-d-alacant-n8236-fr","status":"publish","type":"property","link":"https:\/\/inmobrisa.com\/fr\/property\/venta-de-apartamento-en-san-juan-de-alicante-sant-joan-d-alacant-n8236-fr\/","title":{"rendered":"Venta de Apartamento en San Juan de Alicante\/Sant Joan d&#8217;Alacant &#8211; n8236"},"content":{"rendered":"<p>NOUVEAU COMPLEXE R\u00c9SIDENTIEL A SAN JUAN DE ALICANTENouveau complexe r\u00e9sidentiel de 32 appartements modernes et penthouses situ\u00e9 dans la zone de Nou Nazareth \u00e0 San Juan de Alicante.Il dispose de grandes terrasses, d`un parking, d`une salle de stockage, d`un espace de coworking, d`une salle de sport, d`une piscine et d`espaces paysagers pour faire de votre maison un lieu polyvalent et dynamique.Son architecture, avec une attention particuli\u00e8re aux d\u00e9tails, combine la fonctionnalit\u00e9, le design et l`efficacit\u00e9 \u00e9nerg\u00e9tique d`une maison exclusive.L`\u00e9l\u00e9gance intemporelle de ses finitions et la luminosit\u00e9 apport\u00e9e par sa grande terrasse donnent \u00e0 la maison une profondeur et une continuit\u00e9 avec l`ext\u00e9rieur, cr\u00e9ant ainsi de vastes espaces pour profiter de la vie.Cette r\u00e9sidence s`engage dans la durabilit\u00e9 en r\u00e9alisant des travaux qui optimisent la consommation. Tous nos logements offrent une cote \u00e9nerg\u00e9tique \u00e9lev\u00e9e, de sorte que, tout en contribuant \u00e0 la protection de l`environnement et de la plan\u00e8te, vous b\u00e9n\u00e9ficiez \u00e9galement de grandes \u00e9conomies sur vos factures domestiques.Tous les logements sont \u00e9quip\u00e9s de syst\u00e8mes efficaces de climatisation et de qualit\u00e9 de l`air. Les syst\u00e8mes d`\u00e9clairage \u00e0 LED garantissent une consommation et une dur\u00e9e optimales. Les toilettes sont \u00e0 basse consommation, ce qui permet de r\u00e9aliser d`importantes \u00e9conomies d`eau. Les espaces communs sont aliment\u00e9s en \u00e9nergie par des panneaux solaires install\u00e9s dans le complexe.Le complexe r\u00e9sidentiel est situ\u00e9 \u00e0 Nou Nazareth, l`une des zones les plus recherch\u00e9es de San Juan de Alicante. \u00c0 quelques m\u00e8tres de la mer et entour\u00e9 de tous les services, vous serez \u00e0 seulement 15 minutes du centre d`Alicante et de ses rues anim\u00e9es.Le style de vie que vous trouverez dans cette ville est calme et familial, entour\u00e9 de plages, d`installations sportives et de lieux de divertissement. Vous pourrez vous promener le long de la promenade du front de mer et dans le charmant village, o\u00f9 la gentillesse de ses habitants vous fera vous sentir comme chez vous. En outre, l`h\u00f4tel est situ\u00e9 \u00e0 proximit\u00e9 de l`h\u00f4pital San Juan, de l`universit\u00e9 Miguel Hern\u00e1ndez et de l`a\u00e9roport international d`Alicante.Tout cela en profitant du climat idyllique de la Costa Blanca et de la M\u00e9diterran\u00e9e. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOUVEAU COMPLEXE R\u00c9SIDENTIEL A SAN JUAN DE ALICANTENouveau complexe r\u00e9sidentiel de 32 appartements modernes et penthouses situ\u00e9 dans la zone de Nou Nazareth \u00e0 San Juan de Alicante.Il dispose de grandes terrasses, d`un parking, d`une salle de stockage, d`un espace de coworking, d`une salle de sport, d`une piscine et d`espaces paysagers <\/p>\n","protected":false},"author":3,"featured_media":29123645,"parent":0,"menu_order":0,"template":"","property_type":[5100],"property_status":[5020],"property_feature":[5147,5060,5055],"property_label":[5195],"property_state":[166],"property_city":[394],"property_area":[5397],"class_list":["post-29123642","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-appartements","property_status-vente","property_feature-gymnase","property_feature-jardin","property_feature-piscine","property_label-obra-nova","property_state-alicante","property_city-san-juan-de-alicante-sant-joan-d-alacant","property_area-frank-espinos"],"property_meta":{"fave_agent":["163467"],"fave_agents":["163467"],"fave_agent_display_option":["agent_info"],"custom_permalink":["inmueble\/venta\/apartamento\/alicante\/san-juan-de-alicante-sant-joan-d-alacant\/n8236\/"],"_thumbnail_id":["29123645"],"post_id":["Array"],"original_author":["3"],"property_agent":["163467"],"_edit_lock":["1604137107:1"],"_edit_last":["1"],"fave_property_map_street_view":["show"],"fave_payment_status":["not_paid"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"houzez_manual_expire":["0"],"fave_property_size_prefix":["m&sup2;"],"fave_property_map":["1"],"fave_additional_features_enable":["disable"],"fave_floor_plans_enable":["disable"],"fave_multiunit_plans_enable":["disable"],"fave_prop_homeslider":["no"],"fave_featured":["0"],"fave_property_zip":["03550"],"houzez_geolocation_lat":["38.39038311846497"],"houzez_geolocation_long":["-0.42574705791595313"],"fave_property_location":["38.39038311846497,-0.42574705791595313"],"fave_property_country":["ES"],"fave_comunidadimporte":[""],"fave_comunidadincluida":["0"],"fave_conservacion":["Obra Nueva"],"fave_orientacion":[""],"fave_carpinteriainterior":[""],"fave_carpinteriaexterior":[""],"fave_tiposuelo":[""],"fave_vistas":[""],"fave_ibi":[""],"additional_features":["a:5:{i:0;a:2:{s:29:\"fave_additional_feature_title\";s:12:\"Carpinter\u00eda\";s:29:\"fave_additional_feature_value\";s:0:\"\";}i:1;a:2:{s:29:\"fave_additional_feature_title\";s:21:\"Carpinter\u00eda exterior\";s:29:\"fave_additional_feature_value\";s:0:\"\";}i:2;a:2:{s:29:\"fave_additional_feature_title\";s:6:\"Estado\";s:29:\"fave_additional_feature_value\";s:10:\"Obra Nueva\";}i:3;a:2:{s:29:\"fave_additional_feature_title\";s:6:\"Vistas\";s:29:\"fave_additional_feature_value\";s:0:\"\";}i:4;a:2:{s:29:\"fave_additional_feature_title\";s:12:\"Orientaci\u00f3n\";s:29:\"fave_additional_feature_value\";s:0:\"\";}}"],"referencia":["n8236"],"fave_property_id":["n8236"],"fave_property_bedrooms":["2"],"fave_property_bathrooms":["2"],"fave_property_garage":[""],"fave_property_land":["35"],"ave_property_land_postfix":["m&sup2;"],"fave_property_size":["120"],"fave_property_year":["0"],"fave_energy_global_index":["0 kWh\/m&sup2; \/0 Kg CO2\/m&sup2;"],"fave_energy_class":["A"],"estate_attr_energy_class":["A"],"REAL_HOMES_property_emisiones":["0"],"REAL_HOMES_property_consumo":["0"],"REAL_HOMES_property_letra":["A"],"estate_video":[""],"fave_virtual_tour":[""],"vendidoInmueble":[""],"fave_property_price":["443825"],"fave_property_price_postfix":[""],"fave_property_images":["29123645","29123646","29123647","29123648","29123649","29123650","29123651","29123652","29123653","29123654","29123655","29123656","29123657","29123658","29123659","29123660","29123661","29123662","29123663","29123664","29123665","29123666","29123667"],"houzez_total_property_views":["2"],"houzez_views_by_date":["a:1:{s:10:\"05-13-2026\";i:2;}"],"houzez_recently_viewed":["2026-05-13 21:08:05"],"_elementor_page_assets":["a:0:{}"]},"_links":{"self":[{"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/properties\/29123642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/properties\/29123642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/media\/29123645"}],"wp:attachment":[{"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/media?parent=29123642"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/property_type?post=29123642"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/property_status?post=29123642"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/property_feature?post=29123642"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/property_label?post=29123642"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/property_state?post=29123642"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/property_city?post=29123642"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/property_area?post=29123642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}