{"id":29132695,"date":"2025-05-03T00:33:20","date_gmt":"2025-05-03T00:33:20","guid":{"rendered":"https:\/\/www.inmobrisa.com\/inmueble\/venta\/villas\/murcia\/los-alcazares\/n8861\/"},"modified":"2025-05-03T00:33:20","modified_gmt":"2025-05-03T00:33:20","slug":"venta-de-villa-en-los-alcazares-n8861-fr","status":"publish","type":"property","link":"https:\/\/inmobrisa.com\/fr\/property\/venta-de-villa-en-los-alcazares-n8861-fr\/","title":{"rendered":"Venta de Villa en Los Alc\u00e1zares &#8211; n8861"},"content":{"rendered":"<p>Villas neuves avec piscine priv\u00e9e \u00e0 Los Alc\u00e1zares, Costa C\u00e1lidaVillas modernes exclusives \u00e0 seulement 700 m\u00e8tres de la merD\u00e9couvrez ce lotissement exclusif de 9 villas neuves \u00e0 Los Alc\u00e1zares, l`une des localit\u00e9s les plus pris\u00e9es de la Costa C\u00e1lida pour sa proximit\u00e9 avec la mer, son ambiance d\u00e9tendue et son excellente offre de services. Chaque villa dispose d`une piscine priv\u00e9e, d`un garage couvert ind\u00e9pendant et a \u00e9t\u00e9 con\u00e7ue pour offrir confort, fonctionnalit\u00e9 et style contemporain.Conception en duplex avec solarium et orientation id\u00e9aleLes maisons sont r\u00e9parties sur deux \u00e9tages et disposent de 3 chambres et 2 salles de bains, d`une cuisine ouverte enti\u00e8rement \u00e9quip\u00e9e, d`un grand salon-salle \u00e0 manger, d`une terrasse et d`un jardin au rez-de-chauss\u00e9e, d`une terrasse au premier \u00e9tage et d`un solarium priv\u00e9 sur le toit avec cuisine d`\u00e9t\u00e9. Gr\u00e2ce \u00e0 leurs diff\u00e9rentes orientations, elles permettent de profiter du soleil toute la journ\u00e9e, toute l`ann\u00e9e.\u00c9quipements de haute qualit\u00e9Ces villas sont con\u00e7ues avec des mat\u00e9riaux de premi\u00e8re qualit\u00e9 et offrent :Piscine priv\u00e9e avec douche ext\u00e9rieureCuisine \u00e9quip\u00e9e d`appareils \u00e9lectrom\u00e9nagers : r\u00e9frig\u00e9rateur, four en hauteur, micro-ondes encastr\u00e9, plaque vitroc\u00e9ramique, hotte aspirante et lave-vaisselle int\u00e9gr\u00e9Armoires encastr\u00e9es avec tiroirsSalles de bains compl\u00e8tes avec meuble, miroir avec \u00e9clairage et parois de douchePr\u00e9-installation de la climatisationInstallation de 2 panneaux solairesCuisine d`\u00e9t\u00e9 sur le solariumPlace de parking couverte sur le terrainEmplacement imbattable sur la Costa C\u00e1lidaSitu\u00e9es \u00e0 seulement 700 m\u00e8tres des plages de la Mar Menor, ces maisons vous permettent de profiter d`un environnement naturel unique avec des eaux calmes et chaudes. Los Alc\u00e1zares combine un style de vie d\u00e9tendu avec tous les services \u00e0 port\u00e9e de main : supermarch\u00e9s, restaurants, installations sportives et centres de sant\u00e9. Id\u00e9al aussi bien comme r\u00e9sidence principale que comme r\u00e9sidence secondaire.Distances des points d`int\u00e9r\u00eatPlage du Mar Menor : 0,7 kmTerrains de golf (Roda, La Serena, Mar Menor Golf) : entre 3 et 10 kmA\u00e9roport international de Murcie : 30 kmCartagena : 22 kmCentre commercial Dos Mares : 13 kmPort de plaisance de Los Alc\u00e1zares : 2 kmVotre refuge de soleil et de tranquillit\u00e9 en M\u00e9diterran\u00e9eCes villas offrent la combinaison parfaite entre design moderne, intimit\u00e9, confort et emplacement privil\u00e9gi\u00e9.Contactez-nous d\u00e8s aujourd`hui et prenez rendez-vous pour d\u00e9couvrir votre prochaine maison en bord de mer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Villas neuves avec piscine priv\u00e9e \u00e0 Los Alc\u00e1zares, Costa C\u00e1lidaVillas modernes exclusives \u00e0 seulement 700 m\u00e8tres de la merD\u00e9couvrez ce lotissement exclusif de 9 villas neuves \u00e0 Los Alc\u00e1zares, l`une des localit\u00e9s les plus pris\u00e9es de la Costa C\u00e1lida pour sa proximit\u00e9 avec la mer, son ambiance d\u00e9tendue et son excellente offre de <\/p>\n","protected":false},"author":3,"featured_media":29132698,"parent":0,"menu_order":0,"template":"","property_type":[5171],"property_status":[5020],"property_feature":[5060,5055],"property_label":[5195],"property_state":[5230],"property_city":[5294],"property_area":[5330],"class_list":["post-29132695","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-villas","property_status-vente","property_feature-jardin","property_feature-piscine","property_label-obra-nova","property_state-murcia","property_city-los-alcazares","property_area-serena-golf"],"property_meta":{"fave_agent":["163467"],"fave_agents":["163467"],"fave_agent_display_option":["agent_info"],"custom_permalink":["inmueble\/venta\/villas\/murcia\/los-alcazares\/n8861\/"],"_thumbnail_id":["29132698"],"post_id":["Array"],"original_author":["3"],"property_agent":["163467"],"_edit_lock":["1604137107:1"],"_edit_last":["1"],"fave_property_map_street_view":["show"],"fave_payment_status":["not_paid"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"houzez_manual_expire":["0"],"fave_property_size_prefix":["m&sup2;"],"fave_property_map":["1"],"fave_additional_features_enable":["disable"],"fave_floor_plans_enable":["disable"],"fave_multiunit_plans_enable":["disable"],"fave_prop_homeslider":["no"],"fave_featured":["0"],"fave_property_address":[" Los Alc\u00e1zares, Murcia"],"fave_property_zip":["30710"],"houzez_geolocation_lat":["37.735827606507385"],"houzez_geolocation_long":["-0.8589387881950163"],"fave_property_location":["37.735827606507385,-0.8589387881950163"],"fave_property_country":["ES"],"fave_property_map_address":[" Los Alc\u00e1zares, Murcia, Spain"],"fave_comunidadimporte":[""],"fave_comunidadincluida":["0"],"fave_conservacion":["Obra Nueva"],"fave_orientacion":[""],"fave_carpinteriainterior":[""],"fave_carpinteriaexterior":[""],"fave_tiposuelo":[""],"fave_vistas":[""],"fave_ibi":[""],"additional_features":["a:5:{i:0;a:2:{s:29:\"fave_additional_feature_title\";s:12:\"Carpinter\u00eda\";s:29:\"fave_additional_feature_value\";s:0:\"\";}i:1;a:2:{s:29:\"fave_additional_feature_title\";s:21:\"Carpinter\u00eda exterior\";s:29:\"fave_additional_feature_value\";s:0:\"\";}i:2;a:2:{s:29:\"fave_additional_feature_title\";s:6:\"Estado\";s:29:\"fave_additional_feature_value\";s:10:\"Obra Nueva\";}i:3;a:2:{s:29:\"fave_additional_feature_title\";s:6:\"Vistas\";s:29:\"fave_additional_feature_value\";s:0:\"\";}i:4;a:2:{s:29:\"fave_additional_feature_title\";s:12:\"Orientaci\u00f3n\";s:29:\"fave_additional_feature_value\";s:0:\"\";}}"],"referencia":["n8861"],"fave_property_id":["n8861"],"fave_property_bedrooms":["3"],"fave_property_bathrooms":["2"],"fave_property_garage":[""],"fave_property_land":["170"],"ave_property_land_postfix":["m&sup2;"],"fave_property_size":["101"],"fave_property_year":["0"],"fave_energy_global_index":["0 kWh\/m&sup2; \/0 Kg CO2\/m&sup2;"],"fave_energy_class":["B"],"estate_attr_energy_class":["B"],"REAL_HOMES_property_emisiones":["0"],"REAL_HOMES_property_consumo":["0"],"REAL_HOMES_property_letra":["B"],"estate_video":[""],"fave_virtual_tour":[""],"vendidoInmueble":[""],"fave_property_price":["419900"],"fave_property_price_postfix":[""],"fave_property_images":["29132698","29132699","29132700","29132701","29132702","29132703","29132704","29132705","29132706","29132707","29132708","29132709","29132710","29132711","29132712","29132713","29132714","29132715","29132716","29132717","29132718","29132719","29132720","29132721","29132722","29132723","29132724","29132725","29132726","29132727"],"houzez_total_property_views":["3"],"houzez_views_by_date":["a:1:{s:10:\"05-13-2026\";i:3;}"],"houzez_recently_viewed":["2026-05-13 20:29:54"],"_elementor_page_assets":["a:0:{}"]},"_links":{"self":[{"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/properties\/29132695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/properties\/29132695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/media\/29132698"}],"wp:attachment":[{"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/media?parent=29132695"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/property_type?post=29132695"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/property_status?post=29132695"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/property_feature?post=29132695"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/property_label?post=29132695"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/property_state?post=29132695"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/property_city?post=29132695"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/inmobrisa.com\/fr\/wp-json\/wp\/v2\/property_area?post=29132695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}